{"id":62869,"date":"2019-11-29T00:00:29","date_gmt":"2019-11-29T00:00:29","guid":{"rendered":"https:\/\/infocul.pt\/?p=62869"},"modified":"2019-11-26T17:42:15","modified_gmt":"2019-11-26T17:42:15","slug":"nau-palacio-do-governador-apresenta-propostas-para-o-natal","status":"publish","type":"post","link":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/","title":{"rendered":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-62870 size-large lazyload\" data-src=\"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019-1024x536.jpg\" alt=\"\" width=\"800\" height=\"419\" data-srcset=\"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019-1024x536.jpg 1024w, https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019-300x157.jpg 300w, https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019-768x402.jpg 768w, https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019-390x205.jpg 390w, https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg 1200w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/419;\" \/><\/p>\n<p style=\"font-weight: 400;\">A quadra natal\u00edcia \u00e9 sin\u00f3nimo de partilha, conv\u00edvio e conforto. A pensar nos que n\u00e3o dispensam reunir a fam\u00edlia e os amigos, usufruindo do melhor que a vida nos permite nesta \u00e9poca, o \u00c2nfora, restaurante do hotel NAU Pal\u00e1cio do Governador, apresenta as suas propostas para este Natal e R\u00e9veillon.<!--more--><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">As Boas Festas no restaurante \u00c2nfora celebram-se \u00e0 mesa num ambiente requintado e acolhedor, com vista para a Torre de Bel\u00e9m, complementado pelos saborosos e originais pratos assinados pela chef Vera Silva. Privilegiam-se os produtos tradicionais da \u00e9poca e t\u00edpicos de diversas regi\u00f5es do pa\u00eds, harmoniosamente combinados sob a criatividade e ousadia que aprimora a experi\u00eancia de degusta\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Para a Consoada e Almo\u00e7o de Natal, ambos dispon\u00edveis por 80\u20ac por pessoa, a chef Vera Silva prop\u00f5e um menu composto por tr\u00eas entradas, dois pratos principais e sobremesa.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Inicia-se a refei\u00e7\u00e3o com\u00a0<em>Creme de castanha assada e croutons de bacon<\/em>, a que se segue o\u00a0<em>Bacalhau \u00e0 lagareiro, dentro da batata\u00a0<\/em>e por fim\u00a0<em>Past\u00e9is de massa tenra de marisco<\/em>. Para os pratos principais n\u00e3o falta o produto de elei\u00e7\u00e3o, numa vers\u00e3o sui-generis, o\u00a0<em>L\u00ednguas de Bacalhau numa patanisca, arroz carolino de feij\u00e3o<\/em>, e ainda as\u00a0<em>Bochechas de porco estufadas em Touriga Nacional \u201cGrous 23 Barricas\u201d<\/em>.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Para sobremesa, a sugest\u00e3o imperd\u00edvel \u00e9\u00a0<em>Sonhos perdidos numa espuma de arroz doce\u00a0<\/em>que poder\u00e1 ser conjugada com outras iguarias dispon\u00edveis no buffet de sobremesas natal\u00edcias.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Para a noite de R\u00e9veillon, o hotel NAU Pal\u00e1cio do Governador preparou igualmente um programa especial, dispon\u00edvel por 185\u20ac por pessoa.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">O programa prev\u00ea que, a partir das 19h30, se sirva um cocktail e canap\u00e9s no Occasus Bar. O jantar de Passagem de Ano \u00e9 servido no restaurante \u00c2nfora uma hora depois. Para fechar o ano saboreando o melhor da vida, a equipa do restaurante \u00c2nfora preparou um menu exclusivo. Para entrada serve-se\u00a0<em>Camar\u00e3o da costa, \u201cal ajillo\u201d e pimenta da horta\u00a0<\/em>e\u00a0<em>Lavagante, numa bisque e citronela<\/em>. Do Fundo do Mar surge o\u00a0<em>Pregado e vieira em noisette, numa sinfonia de legumes e pur\u00e9 de salsifi\u00a0<\/em>ap\u00f3s o qual se segue a<em>\u00a0Vitela de leite, pur\u00e9 de batata vitelotte, espargos verdes e brancos assados.<\/em>\u00a0A \u00faltima refei\u00e7\u00e3o do ano n\u00e3o poderia finalizar de melhor forma, com o\u00a0<em>Pudim de vinho do Porto \u201dGraham\u2019s Vintage\u201d\u00a0<\/em>e para os amantes de chocolate eis que fecha a ementa o\u00a0<em>Chocolate negro 70% em cremoso, Ruby e framboesas<\/em>.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Pelas 23h30, os clientes s\u00e3o convidados a subirem novamente ao Occasus Bar onde ser\u00e1 servido uma Flute de Champagne Mo\u00ebt &amp; Chandon para se brindar \u00e0 chegada de 2020 e onde tamb\u00e9m ser\u00e3o oferecidas as tradicionais uvas passa que ajudar\u00e3o a contar os saborosos desejos a realizar no novo ano.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">No primeiro dia do ano tamb\u00e9m \u00e9 poss\u00edvel desfrutar de um abastado e delicioso Brunch de Ano Novo no restaurante \u00c2nfora, por 60\u20ac por pessoa.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Para al\u00e9m das mais variadas op\u00e7\u00f5es de bebidas frias e quentes, p\u00e3o e pastelaria diversa, manteigas e compotas, queijos e charcutaria, iogurtes e cereais, e espelho de salm\u00e3o fumado, este Brunch de dia 1 de janeiro inclui ainda mesas de saladas e frios, de pratos quentes e de doces e pastelaria fina variada.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Em todos os programas as crian\u00e7as entre os 3 e os 12 anos de idade usufruem de um desconto de 50%.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Contacto para Reservas:<\/strong><\/p>\n<p style=\"font-weight: 400;\">212 467 800 ou\u00a0<a href=\"mailto:palaciodogovernador@nauhotels.com\">palaciodogovernador@nauhotels.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A quadra natal\u00edcia \u00e9 sin\u00f3nimo de partilha, conv\u00edvio e conforto. A pensar nos que n\u00e3o dispensam reunir a fam\u00edlia e os amigos, usufruindo do melhor que a vida nos permite nesta \u00e9poca, o \u00c2nfora, restaurante do hotel NAU Pal\u00e1cio do Governador, apresenta as suas propostas para este Natal e R\u00e9veillon.<\/p>\n","protected":false},"author":13,"featured_media":62870,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,13],"tags":[2349,8372],"class_list":["post-62869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidade","category-turismo","tag-natal","tag-nau-palacio-do-governador"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital<\/title>\n<meta name=\"description\" content=\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital\" \/>\n<meta property=\"og:description\" content=\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/\" \/>\n<meta property=\"og:site_name\" content=\"Infocul.pt - Arquivo Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infocul-147816815585015\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-29T00:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redac\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Infoculpt\" \/>\n<meta name=\"twitter:site\" content=\"@Infoculpt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redac\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/\"},\"author\":{\"name\":\"Redac\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/person\\\/f243f45ae8d67639120a7586884f3abc\"},\"headline\":\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal\",\"datePublished\":\"2019-11-29T00:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/\"},\"wordCount\":594,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1200x628_Reveillon_PLG_2019.jpg\",\"keywords\":[\"Natal\",\"Nau Pal\u00e1cio do Governador\"],\"articleSection\":[\"Actualidade\",\"Turismo\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/\",\"name\":\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1200x628_Reveillon_PLG_2019.jpg\",\"datePublished\":\"2019-11-29T00:00:29+00:00\",\"description\":\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1200x628_Reveillon_PLG_2019.jpg\",\"contentUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1200x628_Reveillon_PLG_2019.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/actualidade\\\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/\",\"name\":\"Infocul.pt - Arquivo Digital\",\"description\":\"Arquivo digital da Infocul.pt\",\"publisher\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#organization\",\"name\":\"Infocul.pt\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Infocul_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Infocul_logo-1.png\",\"width\":800,\"height\":800,\"caption\":\"Infocul.pt\"},\"image\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infocul-147816815585015\\\/\",\"https:\\\/\\\/x.com\\\/Infoculpt\",\"http:\\\/\\\/www.pictaram.com\\\/user\\\/infocul.pt\\\/2370423710\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYEB91AGI9FL9ek2i_IaQAA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/person\\\/f243f45ae8d67639120a7586884f3abc\",\"name\":\"Redac\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/151b1b76c598ab5e749407223bd6c1bad4e41c4e95de3c3df83540ebee2deaf8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/151b1b76c598ab5e749407223bd6c1bad4e41c4e95de3c3df83540ebee2deaf8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/151b1b76c598ab5e749407223bd6c1bad4e41c4e95de3c3df83540ebee2deaf8?s=96&d=mm&r=g\",\"caption\":\"Redac\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital","description":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital","og_description":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital","og_url":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/","og_site_name":"Infocul.pt - Arquivo Digital","article_publisher":"https:\/\/www.facebook.com\/Infocul-147816815585015\/","article_published_time":"2019-11-29T00:00:29+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg","type":"image\/jpeg"}],"author":"Redac\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Infoculpt","twitter_site":"@Infoculpt","twitter_misc":{"Escrito por":"Redac\u00e7\u00e3o","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#article","isPartOf":{"@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/"},"author":{"name":"Redac\u00e7\u00e3o","@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/person\/f243f45ae8d67639120a7586884f3abc"},"headline":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal","datePublished":"2019-11-29T00:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/"},"wordCount":594,"commentCount":0,"publisher":{"@id":"https:\/\/infocul.pt\/arquivo\/#organization"},"image":{"@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#primaryimage"},"thumbnailUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg","keywords":["Natal","Nau Pal\u00e1cio do Governador"],"articleSection":["Actualidade","Turismo"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/","url":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/","name":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital","isPartOf":{"@id":"https:\/\/infocul.pt\/arquivo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#primaryimage"},"image":{"@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#primaryimage"},"thumbnailUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg","datePublished":"2019-11-29T00:00:29+00:00","description":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal | Infocul.pt - Arquivo Digital","breadcrumb":{"@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#primaryimage","url":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg","contentUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2019\/11\/1200x628_Reveillon_PLG_2019.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/infocul.pt\/arquivo\/actualidade\/nau-palacio-do-governador-apresenta-propostas-para-o-natal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infocul.pt\/arquivo\/"},{"@type":"ListItem","position":2,"name":"NAU Pal\u00e1cio do Governador apresenta propostas para o Natal"}]},{"@type":"WebSite","@id":"https:\/\/infocul.pt\/arquivo\/#website","url":"https:\/\/infocul.pt\/arquivo\/","name":"Infocul.pt - Arquivo Digital","description":"Arquivo digital da Infocul.pt","publisher":{"@id":"https:\/\/infocul.pt\/arquivo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infocul.pt\/arquivo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/infocul.pt\/arquivo\/#organization","name":"Infocul.pt","url":"https:\/\/infocul.pt\/arquivo\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/logo\/image\/","url":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2018\/12\/Infocul_logo-1.png","contentUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2018\/12\/Infocul_logo-1.png","width":800,"height":800,"caption":"Infocul.pt"},"image":{"@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infocul-147816815585015\/","https:\/\/x.com\/Infoculpt","http:\/\/www.pictaram.com\/user\/infocul.pt\/2370423710","https:\/\/www.youtube.com\/channel\/UCYEB91AGI9FL9ek2i_IaQAA"]},{"@type":"Person","@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/person\/f243f45ae8d67639120a7586884f3abc","name":"Redac\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/151b1b76c598ab5e749407223bd6c1bad4e41c4e95de3c3df83540ebee2deaf8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/151b1b76c598ab5e749407223bd6c1bad4e41c4e95de3c3df83540ebee2deaf8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/151b1b76c598ab5e749407223bd6c1bad4e41c4e95de3c3df83540ebee2deaf8?s=96&d=mm&r=g","caption":"Redac\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/posts\/62869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/comments?post=62869"}],"version-history":[{"count":0,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/posts\/62869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/media\/62870"}],"wp:attachment":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/media?parent=62869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/categories?post=62869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/tags?post=62869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}