{"id":7499,"date":"2016-05-06T12:25:24","date_gmt":"2016-05-06T12:25:24","guid":{"rendered":"http:\/\/infocul.pt\/?p=7499"},"modified":"2016-05-07T22:48:28","modified_gmt":"2016-05-07T22:48:28","slug":"insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira","status":"publish","type":"post","link":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/","title":{"rendered":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira"},"content":{"rendered":"<p>\t<img decoding=\"async\" width=\"160\" height=\"240\" class=\"so-widget-image lazyload\" style=\"--smush-placeholder-width: 160px; --smush-placeholder-aspect-ratio: 160\/240;height: auto; display: block; max-width: 100%;\" data-src=\"http:\/\/infocul.pt\/wp-content\/uploads\/2016\/05\/Insch.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p><strong><span style=\"color: rgb(0, 0, 0); font-family: Calibri;\">Os Insch surgem em 2014, pela m\u00e3o de tr\u00eas amigos de longa data. Da sala de ensaios avistam-se as ondas da Ericeira que rebentam organicamente nas can\u00e7\u00f5es dos Insch em ecos de Nirvana, Deftones, Nine Inch Nails, Bush ou Incubus. Em entrevista ao Infocul.pt a banda falou da concep\u00e7\u00e3o do disco, do percurso que fizeram at\u00e9 criarem a banda e tamb\u00e9m das influencias de musicais dos elementos da banda.<\/span><\/strong><\/p>\n<h3>&nbsp;<\/h3>\n<p>O trio da Ericeira (Manel Gomes (baixo), Miguel Rodrigues (bateria) e Tiago Duarte (guitarra e voz) apresenta o \u00e1lbum de estreia, \u201cSafe Haven\u201d com a grava\u00e7\u00e3o a ficar entregue a Ant\u00f3nio C\u00f4rte-Real (UHF) e Wilson Silva (More Than A Thousand), com participa\u00e7\u00e3o de Pedro Lousada (Blasted Mechanism). A banda ir\u00e1 apresentar o \u00e1lbum ao vivo dia 12 de Maio na sala Est\u00fadio Time Out em Lisboa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fique de seguida com a entrevista na integra \u00e0 banda natural da Ericeira.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Quando surgiu a ideia de criarem a banda?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>N\u00e3o houve exactamente um momento \u201cbora criar uma banda!\u201d mas antes um processo longo, que come\u00e7ou muitos anos antes e percorreu v\u00e1rias outras bandas, com mais amigos. A primeira banda que partilh\u00e1mos foi em 2006 e ao longo dos anos seguintes toc\u00e1mos com mais pessoas mas sempre com o fio comum de estarmos os tr\u00eas juntos. Entre entradas e sa\u00eddas, cheg\u00e1mos a estar completamente parados quase dois anos (2012-2014) at\u00e9 que as saudades falaram mais alto e no in\u00edcio de 2014 volt\u00e1mos timidamente aos ensaios, pela primeira vez como um trio.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Quando pensaram em formar a banda quais os foram os vossos objectivos iniciais?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>O \u00fanico objectivo era mesmo voltamos a tocar juntos, de voltar a ter aquele feeling que s\u00f3 tens quando comungas algo com amigos pr\u00f3ximos e do qual t\u00ednhamos saudades. N\u00e3o tra\u00e7\u00e1mos metas nem compromissos, ali\u00e1s na nossa cabe\u00e7a nunca plane\u00e1mos que as m\u00fasicas chegassem a sair da sala de ensaios.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Sendo voc\u00eas da Ericeira, o mar ser\u00e1 certamente uma fonte de inspira\u00e7\u00e3o. Onde v\u00e3o buscar a inspira\u00e7\u00e3o para os vossos temas?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Todos n\u00f3s fizemos surf na adolesc\u00eancia (entretanto menos) e n\u00e3o h\u00e1 surfista que n\u00e3o tenha uma rela\u00e7\u00e3o especial com o mar, naturalmente. As nossas m\u00fasicas s\u00e3o todas biogr\u00e1ficas, falam dos nossos amores e desamores, das nossas cicatrizes e incertezas, de epis\u00f3dios que nos moldaram a ser quem somos hoje. Tendo esta rela\u00e7\u00e3o de tanta intimidade com cada uma das m\u00fasicas, \u00e9 sempre intenso quando as tocamos, nunca \u00e9 \u201capenas mais uma vez\u201d. A nossa m\u00fasica funciona como uma terapia.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Quais as vossas refer\u00eancias a n\u00edvel musical?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>O mais curioso \u00e9 que se perguntares a cada um o que est\u00e1 a ouvir num dado momento, tirando o nosso \u00e1lbum, \u00e9 muito raro estarmos alinhados [risos]. Todos n\u00f3s fomos adolescentes dos 90s mas naquilo que consideramos as nossas refer\u00eancias, o Manel (baixo) puxa muito ao indie e alternativo (BRMC, NIN, Tool), o Miguel (baterista) tem muito vincada uma cena mais pop e ska (Dave Mathews Band, Jamiroquai, Mad Caddies) e o Tiago (voz e guitarra) puxa ao grunge e nu-metal (Alice In Chains, Incubus, Deftones). Mas influ\u00eancias aparte, o que acontece muitas vezes numa banda \u00e9 que os originais s\u00e3o criados por uma ou duas pessoas, soando mais ou menos numa linha. N\u00f3s esfor\u00e7amo-nos para que cada m\u00fasica tenha a participa\u00e7\u00e3o dos tr\u00eas e temos v\u00e1rios originais que nasceram de uma batida ou de uma linha de baixo.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tendo a banda surgido em 2014, quando come\u00e7ou a ser pensado e concebido o disco de estreia \u201cSafe Haven\u201d?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Com toda a honestidade, a ideia de gravar um \u00e1lbum s\u00f3 surgiu muito depois de quase todas as m\u00fasicas que o integram j\u00e1 estarem praticamente terminadas e de j\u00e1 termos dado v\u00e1rios concertos. Nunca nos preocup\u00e1mos muito com o ponto de vista \u201ccomercial\u201d da nossa m\u00fasica mas antes se a m\u00fasica transmitia o que quer\u00edamos. Acho que j\u00e1 \u00edamos bem a meio de 2015 quando a conversa \u201c\u00e1lbum\u201d surgiu, de forma muito natural e j\u00e1 como um passo l\u00f3gico.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Qual a principal mensagem que tentam transmitir com os temas deste novo disco?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>O disco n\u00e3o tem exactamente um tema, ao ser biogr\u00e1fico, e ao mesmo tempo \u00e9 composta \u00e0 volta do tema mais transversal de todos: a vida. Ao longo das dez m\u00fasicas do \u00e1lbum falamos de separa\u00e7\u00f5es amorosas que deixaram marca, de saudades, de despedida, de frustra\u00e7\u00e3o com a vida, do nascimento de um filho, etc.. N\u00e3o pretendemos ser porta-voz de uma mensagem em particular mas temos tido a felicidade das pessoas se reverem na nossa hist\u00f3ria, nos nossos amores e desamores.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>O ano de 2015 foi de reconhecimento do vosso valor e trabalho. Como foi ao final de um ano de banda, come\u00e7arem a ter o reconhecimento da cr\u00edtica ao vosso trabalho?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Com toda a sinceridade poss\u00edvel, foi inesperado mas muito saboroso. Apesar de compormos primeiramente sobre n\u00f3s e para n\u00f3s, fic\u00e1mos muito orgulhosos com a maior parte das coisas que fomos lendo sobre a nossa m\u00fasica. Mas sabemos que o caminho \u00e9 muito longo e que ainda estamos s\u00f3 a raspar na superf\u00edcie do que \u00e9 \u201cser m\u00fasico\u201d e estar nesta ind\u00fastria, portanto procuramos sempre ter os p\u00e9s na terra. O sentimento geral tem sido de muita surpresa e gratid\u00e3o, globalmente, nunca nos passou pela cabe\u00e7a chegar onde j\u00e1 cheg\u00e1mos e tocar onde j\u00e1 toc\u00e1mos.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>O que est\u00e1 a ser preparado para o concerto de apresenta\u00e7\u00e3o do disco?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Estamos a preparar um concerto totalmente diferente do que temos feito at\u00e9 aqui, em termos t\u00e9cnicos e musicais. Se, por um lado, o Est\u00fadio TimeOut no Mercado da Ribeira nos vai permitir adicionar alguns layers de espect\u00e1culo visual \u00e0 m\u00fasica, por outro lado, estamos a trabalhar muito para que o que colocarmos em palco seja o mais pr\u00f3ximo poss\u00edvel do que se ouve no \u00e1lbum, o que nem sempre \u00e9 f\u00e1cil para um power trio.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Quais as pr\u00f3ximas datas que podem j\u00e1 anunciar?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Temos estado de tal maneira focados a fazer acontecer o \u00e1lbum e tudo o que o materializa (artwork, videoclip, espect\u00e1culo de lan\u00e7amento, etc.) que o que nos apetecia mesmo era tirar um mesinho de f\u00e9rias!<\/strong> [risos] <strong>Mas falando a s\u00e9rio, o melhor \u00e9 acompanharem a agenda no site ou nas redes sociais, vamos andar de norte a sul e talvez nalguns festivais.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Insch surgem em 2014, pela m\u00e3o de tr\u00eas amigos de longa data. Da sala de ensaios avistam-se as ondas da Ericeira que rebentam organicamente nas can\u00e7\u00f5es dos Insch em ecos de Nirvana, Deftones, Nine Inch Nails, Bush ou Incubus. Em entrevista ao Infocul.pt a banda falou da concep\u00e7\u00e3o do disco, do percurso que fizeram [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4],"tags":[447,1285,446],"class_list":["post-7499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-discos","tag-estudio-time-out","tag-insch","tag-mercado-da-ribeira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital<\/title>\n<meta name=\"description\" content=\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital\" \/>\n<meta property=\"og:description\" content=\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/\" \/>\n<meta property=\"og:site_name\" content=\"Infocul.pt - Arquivo Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infocul-147816815585015\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-06T12:25:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-07T22:48:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2016\/05\/Insch-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rui Lavrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Infoculpt\" \/>\n<meta name=\"twitter:site\" content=\"@Infoculpt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rui Lavrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/\"},\"author\":{\"name\":\"Rui Lavrador\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/person\\\/060a108d7f2d85fc6aae505119ee5234\"},\"headline\":\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira\",\"datePublished\":\"2016-05-06T12:25:24+00:00\",\"dateModified\":\"2016-05-07T22:48:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/\"},\"wordCount\":1160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Insch-1.png\",\"keywords\":[\"Est\u00fadio Time Out\",\"Insch\",\"Mercado da Ribeira\"],\"articleSection\":[\"Cultura\",\"Discos\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/\",\"name\":\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Insch-1.png\",\"datePublished\":\"2016-05-06T12:25:24+00:00\",\"dateModified\":\"2016-05-07T22:48:28+00:00\",\"description\":\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Insch-1.png\",\"contentUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Insch-1.png\",\"width\":240,\"height\":240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/cultura\\\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/\",\"name\":\"Infocul.pt - Arquivo Digital\",\"description\":\"Arquivo digital da Infocul.pt\",\"publisher\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#organization\",\"name\":\"Infocul.pt\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Infocul_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Infocul_logo-1.png\",\"width\":800,\"height\":800,\"caption\":\"Infocul.pt\"},\"image\":{\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infocul-147816815585015\\\/\",\"https:\\\/\\\/x.com\\\/Infoculpt\",\"http:\\\/\\\/www.pictaram.com\\\/user\\\/infocul.pt\\\/2370423710\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYEB91AGI9FL9ek2i_IaQAA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infocul.pt\\\/arquivo\\\/#\\\/schema\\\/person\\\/060a108d7f2d85fc6aae505119ee5234\",\"name\":\"Rui Lavrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93febd6873394aa8e975148548a0cb203acfdd42d2c85c5f1408e1a76678aece?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93febd6873394aa8e975148548a0cb203acfdd42d2c85c5f1408e1a76678aece?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93febd6873394aa8e975148548a0cb203acfdd42d2c85c5f1408e1a76678aece?s=96&d=mm&r=g\",\"caption\":\"Rui Lavrador\"},\"description\":\"Iniciou em 2011 o seu percurso em comunica\u00e7\u00e3o social, tendo integrado v\u00e1rios projectos editoriais. Durante o seu percurso integrou projectos como Jornal Hardm\u00fasica, LusoNot\u00edcias, Toureio.pt, ODigital.pt, entre outros \u00d3rg\u00e3os de Comunica\u00e7\u00e3o Social nacionais, na redac\u00e7\u00e3o de v\u00e1rios artigos. Entrevistou a grande maioria das personalidades mais importantes da vida social e cultural do pa\u00eds, destacando-se, tamb\u00e9m, na aprecia\u00e7\u00e3o de v\u00e1rios espect\u00e1culos. Durante o seu percurso, deu a conhecer v\u00e1rios artistas, at\u00e9 ent\u00e3o desconhecidos, ao grande p\u00fablico. Em 2015 criou e fundou o Infocul.pt, projecto no qual assume a direc\u00e7\u00e3o editorial.\",\"sameAs\":[\"http:\\\/\\\/www.infocul.pt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital","description":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital","og_description":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital","og_url":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/","og_site_name":"Infocul.pt - Arquivo Digital","article_publisher":"https:\/\/www.facebook.com\/Infocul-147816815585015\/","article_published_time":"2016-05-06T12:25:24+00:00","article_modified_time":"2016-05-07T22:48:28+00:00","og_image":[{"width":240,"height":240,"url":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2016\/05\/Insch-1.png","type":"image\/png"}],"author":"Rui Lavrador","twitter_card":"summary_large_image","twitter_creator":"@Infoculpt","twitter_site":"@Infoculpt","twitter_misc":{"Escrito por":"Rui Lavrador","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#article","isPartOf":{"@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/"},"author":{"name":"Rui Lavrador","@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/person\/060a108d7f2d85fc6aae505119ee5234"},"headline":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira","datePublished":"2016-05-06T12:25:24+00:00","dateModified":"2016-05-07T22:48:28+00:00","mainEntityOfPage":{"@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/"},"wordCount":1160,"commentCount":0,"publisher":{"@id":"https:\/\/infocul.pt\/arquivo\/#organization"},"image":{"@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#primaryimage"},"thumbnailUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2016\/05\/Insch-1.png","keywords":["Est\u00fadio Time Out","Insch","Mercado da Ribeira"],"articleSection":["Cultura","Discos"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/","url":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/","name":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital","isPartOf":{"@id":"https:\/\/infocul.pt\/arquivo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#primaryimage"},"image":{"@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#primaryimage"},"thumbnailUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2016\/05\/Insch-1.png","datePublished":"2016-05-06T12:25:24+00:00","dateModified":"2016-05-07T22:48:28+00:00","description":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira | Infocul.pt - Arquivo Digital","breadcrumb":{"@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#primaryimage","url":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2016\/05\/Insch-1.png","contentUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2016\/05\/Insch-1.png","width":240,"height":240},{"@type":"BreadcrumbList","@id":"https:\/\/infocul.pt\/arquivo\/cultura\/insch-apresentam-o-primeiro-disco-em-entrevista-ao-infocul-e-com-concerto-no-time-out-mercado-da-ribeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infocul.pt\/arquivo\/"},{"@type":"ListItem","position":2,"name":"Insch apresentam o primeiro disco em entrevista ao Infocul e com concerto no Time Out Mercado da Ribeira"}]},{"@type":"WebSite","@id":"https:\/\/infocul.pt\/arquivo\/#website","url":"https:\/\/infocul.pt\/arquivo\/","name":"Infocul.pt - Arquivo Digital","description":"Arquivo digital da Infocul.pt","publisher":{"@id":"https:\/\/infocul.pt\/arquivo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infocul.pt\/arquivo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/infocul.pt\/arquivo\/#organization","name":"Infocul.pt","url":"https:\/\/infocul.pt\/arquivo\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/logo\/image\/","url":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2018\/12\/Infocul_logo-1.png","contentUrl":"https:\/\/infocul.pt\/arquivo\/wp-content\/uploads\/2018\/12\/Infocul_logo-1.png","width":800,"height":800,"caption":"Infocul.pt"},"image":{"@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infocul-147816815585015\/","https:\/\/x.com\/Infoculpt","http:\/\/www.pictaram.com\/user\/infocul.pt\/2370423710","https:\/\/www.youtube.com\/channel\/UCYEB91AGI9FL9ek2i_IaQAA"]},{"@type":"Person","@id":"https:\/\/infocul.pt\/arquivo\/#\/schema\/person\/060a108d7f2d85fc6aae505119ee5234","name":"Rui Lavrador","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/93febd6873394aa8e975148548a0cb203acfdd42d2c85c5f1408e1a76678aece?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93febd6873394aa8e975148548a0cb203acfdd42d2c85c5f1408e1a76678aece?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93febd6873394aa8e975148548a0cb203acfdd42d2c85c5f1408e1a76678aece?s=96&d=mm&r=g","caption":"Rui Lavrador"},"description":"Iniciou em 2011 o seu percurso em comunica\u00e7\u00e3o social, tendo integrado v\u00e1rios projectos editoriais. Durante o seu percurso integrou projectos como Jornal Hardm\u00fasica, LusoNot\u00edcias, Toureio.pt, ODigital.pt, entre outros \u00d3rg\u00e3os de Comunica\u00e7\u00e3o Social nacionais, na redac\u00e7\u00e3o de v\u00e1rios artigos. Entrevistou a grande maioria das personalidades mais importantes da vida social e cultural do pa\u00eds, destacando-se, tamb\u00e9m, na aprecia\u00e7\u00e3o de v\u00e1rios espect\u00e1culos. Durante o seu percurso, deu a conhecer v\u00e1rios artistas, at\u00e9 ent\u00e3o desconhecidos, ao grande p\u00fablico. Em 2015 criou e fundou o Infocul.pt, projecto no qual assume a direc\u00e7\u00e3o editorial.","sameAs":["http:\/\/www.infocul.pt"]}]}},"_links":{"self":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/posts\/7499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/comments?post=7499"}],"version-history":[{"count":0,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/posts\/7499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/media\/7501"}],"wp:attachment":[{"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/media?parent=7499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/categories?post=7499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infocul.pt\/arquivo\/wp-json\/wp\/v2\/tags?post=7499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}